{"id":1955,"date":"2022-09-05T08:30:28","date_gmt":"2022-09-05T06:30:28","guid":{"rendered":"https:\/\/lieferanten-verzeichnis.info\/metawell\/?post_type=readypages&#038;p=1955"},"modified":"2022-09-06T10:48:09","modified_gmt":"2022-09-06T08:48:09","slug":"ansprechpartner-funktionsbereiche","status":"publish","type":"page","link":"https:\/\/lieferanten-verzeichnis.info\/metawell\/ansprechpartner-funktionsbereiche\/","title":{"rendered":"Ansprechpartner FUNKTIONSBEREICHE"},"content":{"rendered":"<h4>Ihre ANSPRECHPARTNER bei \t\tMetawell GmbH\r\n<br>\r\nmetal sandwich technology:<\/h4>\n<p style=\"text-align: right;\"><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p>&nbsp;<\/p>\n<div class=\" accordion-ckiggn style2 magee-shortcode panel-group magee-accordion accordion-boxed\" role=\"tablist\" aria-multiselectable=\"yes\" id=\"accordion-ckiggn\"> <div class=\"panel panel-default \" id=\"panelaccordion-ckiggn-1\"><div class=\"panel-heading\" role=\"tab\" id=\"headingcollapseaccordion-ckiggn-1\">\r\n\t\t\t\t<a class=\"accordion-toggle \" data-toggle=\"collapse\" data-parent=\"#accordion-ckiggn\" href=\"#collapseaccordion-ckiggn-1\" aria-expanded=\"true\" aria-controls=\"collapseaccordion-ckiggn-1\">\r\n\t\t\t\t\t<h4 class=\"panel-title\">\r\n\t\t\t\t\t\t\t(+) FUNKTIONSBEREICHE\r\n\t\t\t\t\t<\/h4>\r\n\t\t\t\t<\/a>\r\n\t\t\t<\/div>\r\n\t\t\t<div id=\"collapseaccordion-ckiggn-1\" class=\"panel-collapse collapse in\" role=\"tabpanel\" aria-labelledby=\"headingcollapseaccordion-ckiggn-1\" aria-expanded=\"true\">\r\n\t\t\t\t<div class=\"panel-body\">\r\n\t\t\t\t\t\n<section class=\" magee-shortcode section magee-section section-7s954r\" id=\"\"> <div class=\"section-content\"><div class=\"container-fullwidth\">\n<p>&nbsp;<\/p>\n<div data-post-id=\"3083\" class=\"insert-page insert-page-3083 \"><p>ANSPRECHPARTNER in den FUNKTIONSBEREICHEN des Unternehmens:<\/p>\n<p><a class=\"fasc-button fasc-size-medium fasc-type-flat\" style=\"background-color: #e312af;color: #ffffff\" href=\"https:\/\/www.metawell.com\/kontakt\/\">Ansprechpartner<\/a><\/p>\n<\/div>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/div><\/div> <\/section>\n\r\n\t\t\t\t\t<div class=\"clear\"><\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t<\/div> <\/div>\n<p style=\"text-align: right;\"><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p style=\"text-align: right;\">&nbsp;<\/p>\n<p style=\"text-align: right;\"><span style=\"color: #ffffff; font-size: 12pt;\">&#8211;<\/span><\/p>\n<hr>\n<p style=\"text-align: right;\"><span style=\"color: #ffffff; font-size: 12pt;\">.<\/span><\/p>\n<blockquote>\n<p><span style=\"font-size: 12pt;\">Kennen Sie schon unsere neuesten Stellenausschreibungen? &gt;&gt;&gt;&nbsp;<a class=\"fasc-button fasc-size-medium fasc-type-popout fasc-style-bold\" style=\"background-color: #000000; color: #ffffff;\" href=\"https:\/\/lieferanten-verzeichnis.info\/metawell\/stellenangebote\/\">STELLENANGEBOTE<\/a><\/span><\/p>\n<\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Ihre ANSPRECHPARTNER bei : . &nbsp; . &nbsp; &#8211; . Kennen Sie schon unsere neuesten Stellenausschreibungen? &gt;&gt;&gt;&nbsp;STELLENANGEBOTE<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"categories":[21],"tags":[310,304,309],"class_list":["post-1955","page","type-page","status-publish","hentry","category-ansprechpartner","tag-ansprechpartner-funktionsbereiche","tag-ready-page-07-01-ansprechpartner-funktionsbereiche","tag-ready-page-07-ansprechpartner"],"_links":{"self":[{"href":"https:\/\/lieferanten-verzeichnis.info\/metawell\/wp-json\/wp\/v2\/pages\/1955","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lieferanten-verzeichnis.info\/metawell\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/lieferanten-verzeichnis.info\/metawell\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/lieferanten-verzeichnis.info\/metawell\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lieferanten-verzeichnis.info\/metawell\/wp-json\/wp\/v2\/comments?post=1955"}],"version-history":[{"count":4,"href":"https:\/\/lieferanten-verzeichnis.info\/metawell\/wp-json\/wp\/v2\/pages\/1955\/revisions"}],"predecessor-version":[{"id":2121,"href":"https:\/\/lieferanten-verzeichnis.info\/metawell\/wp-json\/wp\/v2\/pages\/1955\/revisions\/2121"}],"wp:attachment":[{"href":"https:\/\/lieferanten-verzeichnis.info\/metawell\/wp-json\/wp\/v2\/media?parent=1955"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lieferanten-verzeichnis.info\/metawell\/wp-json\/wp\/v2\/categories?post=1955"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lieferanten-verzeichnis.info\/metawell\/wp-json\/wp\/v2\/tags?post=1955"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}